{"id":4711,"date":"2019-09-20T10:58:00","date_gmt":"2019-09-20T10:58:00","guid":{"rendered":"https:\/\/expedia.blog.es.sandwave.dev\/stories\/?p=4711"},"modified":"2021-09-01T22:10:03","modified_gmt":"2021-09-01T22:10:03","slug":"10-cosas-que-ver-en-gandia-ademas-de-sus-playas","status":"publish","type":"post","link":"https:\/\/www.expedia.es\/stories\/10-cosas-que-ver-en-gandia-ademas-de-sus-playas\/","title":{"rendered":"10 cosas que ver en Gand\u00eda, adem\u00e1s de sus playas"},"content":{"rendered":"<p>&#8220;\u00bfHas elegido tu <a href=\"https:\/\/www.expedia.es\/Gandia-Hoteles.d182327.Guia-Viajes-Hoteles\">alojamiento en Gand\u00eda<\/a> por sus maravillosas playas y calas? Si es as\u00ed, \u00a1has acertado de pleno! Y es que uno de los grandes atractivos de esta bonita localidad valenciana es su privilegiada situaci\u00f3n a orillas del Mediterr\u00e1neo. Desde luego, las fin\u00edsimas arenas, las tranquilas aguas y el clima envidiable (as\u00ed como los miles de turistas que se acercan hasta su costa verano tras verano) nos dan la raz\u00f3n: las playas de Gand\u00eda lo tienen todo para disfrutar de unos d\u00edas de sol.<\/p>\n<p>Pero ah\u00ed no queda la cosa, ni mucho menos. Si buscas complementar tus jornadas de playa con rutas culturales, actividades de ocio y buena gastronom\u00eda, no podr\u00edas haber elegido mejor destino. Por eso, como las vacaciones dan para mucho (\u00a1y Gand\u00eda tambi\u00e9n!), te hemos preparado una lista con las 10 cosas que tienes que ver en Gand\u00eda: un recorrido por los museos m\u00e1s interesantes, los monumentos m\u00e1s importantes y los rincones con m\u00e1s encanto de esta peque\u00f1a localidad. \u00bfNos acompa\u00f1as?<\/p>\n<p>### 1. El Palacio Ducal de Gand\u00eda<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/185000\/185266.jpg\" alt=\"1024px-Gandia.Palacio_ducal.jpg?1571220367\" \/><\/p>\n<p><em>Cr\u00e9dito de la fotograf\u00eda: Gafotas [CC BY SA 3.0 (<a href=\"http:\/\/creativecommons.org\/licenses\/by-sa\/3.0\/\">http:\/\/creativecommons.org\/licenses\/by-sa\/3.0\/<\/a>)]<\/em><\/p>\n<p>Tambi\u00e9n conocido como el &#8220;Palacio de los Borja&#8221;, es uno de los monumentos m\u00e1s importantes de la localidad, declarado Bien de Inter\u00e9s Cultural. Se trata de uno de los ejemplos m\u00e1s impresionantes de la arquitectura g\u00f3tica valenciana y una de las mansiones m\u00e1s importantes de la Corona de Arag\u00f3n, por lo que no puede faltar en tu ruta. Y como tienes la posibilidad de hacer visitas guiadas o por libre, podr\u00e1s disfrutar de esta joya como m\u00e1s te apetezca.<\/p>\n<p>### 2. El Museo Fallero<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/185000\/185267.jpg\" alt=\"Falla_Gandia.jpg?1571220415\" \/><\/p>\n<p>Este museo es un aut\u00e9ntico homenaje a la fiesta por excelencia de la Comunidad Valenciana: las Fallas. Ubicado en un moderno edificio, el Museo Fallero te acerca a los trajes, la m\u00fasica y las tradiciones m\u00e1s arraigadas del universo fallero para que salgas como un aut\u00e9ntico experto. Y si te quedas con ganas de ampliar tu recorrido cultural por la localidad, tenemos otra parada para ti: el Museo de Santa Clara, lleno de maravillosas muestras de pintura, escultura y orfebrer\u00eda.<\/p>\n<p>### 3. La Colegiata de Santa Mar\u00eda<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/185000\/185268.jpg\" alt=\"Colegiata_de_Santa_Mari%CC%81a.jpg?1571220429\" \/><\/p>\n<p>Declarada Monumento Hist\u00f3rico Nacional, esta iglesia cat\u00f3lica (tambi\u00e9n conocida como &#8220;La Seu&#8221;) es otro magn\u00edfico ejemplo del g\u00f3tico valenciano. Adem\u00e1s, como se encuentra en pleno centro hist\u00f3rico, es imposible perd\u00e9rsela. Su construcci\u00f3n data nada menos que del a\u00f1o 1499, por lo que ya te puedes imaginar toda la historia que se respira en su interior.<\/p>\n<p>### 4. El mercado del Prado<\/p>\n<p>Despu\u00e9s de unas horas en Gand\u00eda, seguro que el hambre empieza a hacer mella y est\u00e1s deseando probar alguna de las delicias gastron\u00f3micas m\u00e1s t\u00edpicas de la Comunidad Valenciana. Pues nada mejor que hacerlo en el mercado del Prado, donde podr\u00e1s degustar platos tradicionales, como el arroz o la fideu\u00e1, en alguno de los animados bares y restaurantes que alberga. \u00a1Imprescindible!<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/185000\/185269.jpg\" alt=\"Fideua.jpg?1571220445\" \/><\/p>\n<p>### 5. El puerto<\/p>\n<p>Para bajar la comida despu\u00e9s de un buen atrac\u00f3n de delicias valencianas, lo mejor es perderte por el puerto de Gand\u00eda, que funciona como puerto deportivo, pesquero y comercial, \u00a1ah\u00ed es nada! Perfecto para estirar las piernas y disfrutar de un entorno con agradables vistas.<\/p>\n<p>### 6. La Casa de Cultura<\/p>\n<p>La Casa de Cultura Marqu\u00e9s Gonz\u00e1lez de Quir\u00f3s es el n\u00facleo cultural y art\u00edstico de la localidad, y se encuentra en el casco hist\u00f3rico. Aunque solo por ver el elegante edificio ya merece la pena la visita, te recomendamos echar un vistazo a los conciertos, exposiciones, espect\u00e1culos y obras de teatro que se suelen organizar aqu\u00ed durante todo el a\u00f1o.<\/p>\n<p>### 7. El castillo de Bair\u00e9n<\/p>\n<p>Tambi\u00e9n conocido como el castillo de San Juan, esta fortaleza en ruinas fue una de las m\u00e1s importantes de la regi\u00f3n y ofrece unas vistas impresionantes de la costa valenciana. Si quieres conocer los objetos que hab\u00eda en su interior, eso s\u00ed, ac\u00e9rcate al Museo Arqueol\u00f3gico de Gand\u00eda, donde est\u00e1n expuestos.<\/p>\n<p>### 8. El Ullal de l&#8217;Estany<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/185000\/185270.jpg\" alt=\"Ullal_de_l&#039;Estany_i_nu%CC%81vols__Gandia.jpg?1571220474\" \/><\/p>\n<p>_Cr\u00e9dito de la fotograf\u00eda: Joanbanjo [CC BY SA 4.0 (<a href=\"https:\/\/creativecommons.org\/licenses\/by-sa\/4.0)]_A\">https:\/\/creativecommons.org\/licenses\/by-sa\/4.0)]_A<\/a> los pies del castillo se encuentra el Ullal de L&#8217;Estany, un humedal de agua dulce con diversas especies animales y vegetales perfecto para conectar con la naturaleza. Puedes visitarlo a pie o en bicicleta, y completar tu paseo con una visita al Aula Natura (el centro de interpretaci\u00f3n del humedal) y a la Alquer\u00eda del Duc, un edificio fortificado construido en el siglo XIV.<\/p>\n<p>### 9. La cueva del Parpall\u00f3<\/p>\n<p>Si lo tuyo es el arte rupestre, la cueva del Parpall\u00f3 te fascinar\u00e1. Se trata de uno de los yacimientos prehist\u00f3ricos m\u00e1s importantes del Paleol\u00edtico superior de toda Europa y est\u00e1 catalogado como Bien de Inter\u00e9s Cultural. No dudes en reservar una visita guiada por su interior, \u00a1es impresionante!<\/p>\n<p>### 10. Y, por supuesto, \u00a1sus playas!<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/185000\/185271.jpg\" alt=\"Playa_de_Gandia.jpg?1571220523\" \/><\/p>\n<p>Despu\u00e9s de empaparte de cultura, gastronom\u00eda, naturaleza e historia, ahora s\u00ed, te has ganado un buen chapuz\u00f3n en las mejores playas de Gand\u00eda. Para disfrutar de todos los servicios, ac\u00e9rcate a la playa del Norte; si prefieres un lugar m\u00e1s apartado, tu sitio est\u00e1 en la playa de Venecia. Otras playas m\u00e1s peque\u00f1as pero tambi\u00e9n recomendables son la de L&#8217;Ahuir, un para\u00edso para los amantes del nudismo, o la de Rafalcaid, delimitada por peque\u00f1as dunas.<\/p>\n<p>Si has llegado hasta aqu\u00ed, Gand\u00eda ya no tiene secretos para ti. Como has visto, tienes mucho que hacer, as\u00ed que no pierdas tiempo y <a href=\"https:\/\/www.expedia.es\/Gandia.d182327.Viajes-y-Vacaciones\">reserva ya tu viaje<\/a> a esta encantadora localidad valenciana. Y si te queda algo de tiempo despu\u00e9s de visitar todas nuestras propuestas, \u00bfpor qu\u00e9 no <a href=\"https:\/\/www.expedia.es\/Alquiler-De-Coches-En-Gandia.d182327.Guia-De-Coches-De-Alquiler\">alquilar un coche<\/a> y visitar alguno de los muchos puntos de inter\u00e9s cercanos? A una hora o menos en coche tienes el Oceanogr\u00e0fic, el Bioparc o Terra M\u00edtica, tres destinos muy recomendables para un viaje en familia.<\/p>\n<p><em>Fotograf\u00eda de portada: Joanbanjo [CC BY SA 4.0 (<a href=\"https:\/\/creativecommons.org\/licenses\/by-sa\/4.0\">https:\/\/creativecommons.org\/licenses\/by-sa\/4.0<\/a>)]<\/em>&#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Descubre todos los rincones de visita obligada durante tu escapada a Gand\u00eda: museos, monumentos, espacios naturales&#8230; \u00a1Prohibido perd\u00e9rselos!<\/p>\n","protected":false},"author":6,"featured_media":4713,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[85,86,102],"tags":[17,38,10],"authors":[],"class_list":["post-4711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-day-trips","category-vacation-ideas","category-beach","tag-beach","tag-day-trips","tag-vacation-ideas","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>10 cosas que ver en Gand\u00eda, adem\u00e1s de sus playas | Explore de Expedia<\/title>\n<meta name=\"description\" content=\"Descubre todos los rincones de visita obligada durante tu escapada a Gand\u00eda: museos, monumentos, espacios naturales... \u00a1Prohibido perd\u00e9rselos!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.expedia.es\/stories\/10-cosas-que-ver-en-gandia-ademas-de-sus-playas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 cosas que ver en Gand\u00eda, adem\u00e1s de sus playas\" \/>\n<meta property=\"og:description\" content=\"Descubre todos los rincones de visita obligada durante tu escapada a Gand\u00eda: museos, monumentos, espacios naturales... \u00a1Prohibido perd\u00e9rselos!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.expedia.es\/stories\/10-cosas-que-ver-en-gandia-ademas-de-sus-playas\/\" \/>\n<meta property=\"og:site_name\" content=\"Expedia.es\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-20T10:58:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-01T22:10:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/185000\/185265-share-image.jpg\" \/>\n<meta name=\"author\" content=\"Expedia Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Expedia Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.expedia.es\/stories\/10-cosas-que-ver-en-gandia-ademas-de-sus-playas\/\",\"url\":\"https:\/\/www.expedia.es\/stories\/10-cosas-que-ver-en-gandia-ademas-de-sus-playas\/\",\"name\":\"10 cosas que ver en Gand\u00eda, adem\u00e1s de sus playas | Explore de Expedia\",\"isPartOf\":{\"@id\":\"https:\/\/www.expedia.es\/stories\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.expedia.es\/stories\/10-cosas-que-ver-en-gandia-ademas-de-sus-playas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.expedia.es\/stories\/10-cosas-que-ver-en-gandia-ademas-de-sus-playas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.expedia.es\/stories\/wp-content\/uploads\/2021\/06\/185265-share-image.jpg\",\"datePublished\":\"2019-09-20T10:58:00+00:00\",\"dateModified\":\"2021-09-01T22:10:03+00:00\",\"author\":{\"@id\":\"https:\/\/www.expedia.es\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\"},\"description\":\"Descubre todos los rincones de visita obligada durante tu escapada a Gand\u00eda: museos, monumentos, espacios naturales... \u00a1Prohibido perd\u00e9rselos!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.expedia.es\/stories\/10-cosas-que-ver-en-gandia-ademas-de-sus-playas\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.expedia.es\/stories\/10-cosas-que-ver-en-gandia-ademas-de-sus-playas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.es\/stories\/10-cosas-que-ver-en-gandia-ademas-de-sus-playas\/#primaryimage\",\"url\":\"https:\/\/www.expedia.es\/stories\/wp-content\/uploads\/2021\/06\/185265-share-image.jpg\",\"contentUrl\":\"https:\/\/www.expedia.es\/stories\/wp-content\/uploads\/2021\/06\/185265-share-image.jpg\",\"width\":1024,\"height\":685},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.expedia.es\/stories\/10-cosas-que-ver-en-gandia-ademas-de-sus-playas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Explore\",\"item\":\"https:\/\/www.expedia.es\/stories\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Excursiones\",\"item\":\"https:\/\/www.expedia.es\/stories\/day-trips\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"10 cosas que ver en Gand\u00eda, adem\u00e1s de sus playas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.expedia.es\/stories\/#website\",\"url\":\"https:\/\/www.expedia.es\/stories\/\",\"name\":\"Expedia.es\",\"description\":\"Tu viaje comienza aqu\u00ed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.expedia.es\/stories\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.expedia.es\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\",\"name\":\"Expedia Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.es\/stories\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5c89c0867307ea4026e6797b616f717994e19c3a2e08e92acc2ad7a7f0ba483e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5c89c0867307ea4026e6797b616f717994e19c3a2e08e92acc2ad7a7f0ba483e?s=96&d=mm&r=g\",\"caption\":\"Expedia Team\"},\"url\":\"https:\/\/www.expedia.es\/stories\/author\/expedia-team\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10 cosas que ver en Gand\u00eda, adem\u00e1s de sus playas | Explore de Expedia","description":"Descubre todos los rincones de visita obligada durante tu escapada a Gand\u00eda: museos, monumentos, espacios naturales... \u00a1Prohibido perd\u00e9rselos!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.expedia.es\/stories\/10-cosas-que-ver-en-gandia-ademas-de-sus-playas\/","og_locale":"en_US","og_type":"article","og_title":"10 cosas que ver en Gand\u00eda, adem\u00e1s de sus playas","og_description":"Descubre todos los rincones de visita obligada durante tu escapada a Gand\u00eda: museos, monumentos, espacios naturales... \u00a1Prohibido perd\u00e9rselos!","og_url":"https:\/\/www.expedia.es\/stories\/10-cosas-que-ver-en-gandia-ademas-de-sus-playas\/","og_site_name":"Expedia.es","article_published_time":"2019-09-20T10:58:00+00:00","article_modified_time":"2021-09-01T22:10:03+00:00","og_image":[{"url":"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/185000\/185265-share-image.jpg"}],"author":"Expedia Team","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Expedia Team","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.expedia.es\/stories\/10-cosas-que-ver-en-gandia-ademas-de-sus-playas\/","url":"https:\/\/www.expedia.es\/stories\/10-cosas-que-ver-en-gandia-ademas-de-sus-playas\/","name":"10 cosas que ver en Gand\u00eda, adem\u00e1s de sus playas | Explore de Expedia","isPartOf":{"@id":"https:\/\/www.expedia.es\/stories\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.expedia.es\/stories\/10-cosas-que-ver-en-gandia-ademas-de-sus-playas\/#primaryimage"},"image":{"@id":"https:\/\/www.expedia.es\/stories\/10-cosas-que-ver-en-gandia-ademas-de-sus-playas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.expedia.es\/stories\/wp-content\/uploads\/2021\/06\/185265-share-image.jpg","datePublished":"2019-09-20T10:58:00+00:00","dateModified":"2021-09-01T22:10:03+00:00","author":{"@id":"https:\/\/www.expedia.es\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389"},"description":"Descubre todos los rincones de visita obligada durante tu escapada a Gand\u00eda: museos, monumentos, espacios naturales... \u00a1Prohibido perd\u00e9rselos!","breadcrumb":{"@id":"https:\/\/www.expedia.es\/stories\/10-cosas-que-ver-en-gandia-ademas-de-sus-playas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.expedia.es\/stories\/10-cosas-que-ver-en-gandia-ademas-de-sus-playas\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.es\/stories\/10-cosas-que-ver-en-gandia-ademas-de-sus-playas\/#primaryimage","url":"https:\/\/www.expedia.es\/stories\/wp-content\/uploads\/2021\/06\/185265-share-image.jpg","contentUrl":"https:\/\/www.expedia.es\/stories\/wp-content\/uploads\/2021\/06\/185265-share-image.jpg","width":1024,"height":685},{"@type":"BreadcrumbList","@id":"https:\/\/www.expedia.es\/stories\/10-cosas-que-ver-en-gandia-ademas-de-sus-playas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Explore","item":"https:\/\/www.expedia.es\/stories\/"},{"@type":"ListItem","position":2,"name":"Excursiones","item":"https:\/\/www.expedia.es\/stories\/day-trips\/"},{"@type":"ListItem","position":3,"name":"10 cosas que ver en Gand\u00eda, adem\u00e1s de sus playas"}]},{"@type":"WebSite","@id":"https:\/\/www.expedia.es\/stories\/#website","url":"https:\/\/www.expedia.es\/stories\/","name":"Expedia.es","description":"Tu viaje comienza aqu\u00ed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.expedia.es\/stories\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.expedia.es\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389","name":"Expedia Team","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.es\/stories\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5c89c0867307ea4026e6797b616f717994e19c3a2e08e92acc2ad7a7f0ba483e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c89c0867307ea4026e6797b616f717994e19c3a2e08e92acc2ad7a7f0ba483e?s=96&d=mm&r=g","caption":"Expedia Team"},"url":"https:\/\/www.expedia.es\/stories\/author\/expedia-team\/"}]}},"_links":{"self":[{"href":"https:\/\/www.expedia.es\/stories\/wp-json\/wp\/v2\/posts\/4711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.expedia.es\/stories\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.expedia.es\/stories\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.expedia.es\/stories\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.expedia.es\/stories\/wp-json\/wp\/v2\/comments?post=4711"}],"version-history":[{"count":2,"href":"https:\/\/www.expedia.es\/stories\/wp-json\/wp\/v2\/posts\/4711\/revisions"}],"predecessor-version":[{"id":8149,"href":"https:\/\/www.expedia.es\/stories\/wp-json\/wp\/v2\/posts\/4711\/revisions\/8149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.expedia.es\/stories\/wp-json\/wp\/v2\/media\/4713"}],"wp:attachment":[{"href":"https:\/\/www.expedia.es\/stories\/wp-json\/wp\/v2\/media?parent=4711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.expedia.es\/stories\/wp-json\/wp\/v2\/categories?post=4711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.expedia.es\/stories\/wp-json\/wp\/v2\/tags?post=4711"},{"taxonomy":"authors","embeddable":true,"href":"https:\/\/www.expedia.es\/stories\/wp-json\/wp\/v2\/authors?post=4711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}