{"id":3610,"date":"2017-07-12T03:07:00","date_gmt":"2017-07-12T03:07:00","guid":{"rendered":"https:\/\/expedia.blog.es.sandwave.dev\/stories\/?p=3610"},"modified":"2021-09-01T22:06:22","modified_gmt":"2021-09-01T22:06:22","slug":"gijon-10-cosas-imprescindibles","status":"publish","type":"post","link":"https:\/\/www.expedia.es\/stories\/gijon-10-cosas-imprescindibles\/","title":{"rendered":"Gij\u00f3n: 10 cosas imprescindibles"},"content":{"rendered":"<p>&#8220;Brindar con unas <em>sidrinas<\/em><\/p>\n<p>Dicen que <em>Poca sidra fae falta pa apagar una gran sed<\/em>, de ah\u00ed que se beba en peque\u00f1as cantidades o <em>culines.<\/em> Escanciada desde lo alto, tiene que beberse de una sola vez y lanzar el poso sobrante al suelo. Para aprender a beber y escanciar sidra como un asturiano nada mejor que acudir a alg\u00fan <em>llagar<\/em>, local en donde se produce esta bebida tradicional elaborada con manzanas, normalmente parecido a un merendero. En La Galana (Plaza Mayor, 10) puedes acompa\u00f1ar cada trago de un ambiente genial.<\/p>\n<figure class='caption' data-markdown='1'>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/96000\/96864.jpg\" alt=\"\" \/><figcaption>La sidra tiene que estar debidamente escanciada para tener su delicioso sabor  <br \/>Escanciando sidra courtesy \u00a9 2006 Infoasturias &#8211; Jos\u00e9 Su\u00e1rez Asturias Turismo Photo<\/figcaption><\/figure>\n<p>Comer cachopo<\/p>\n<p>Est\u00e1 claro que el norte es de buen comer. Asturias es el templo de deliciosos platos de los que el rey indiscutible es el cachopo, dos finos filetes de ternera empanados y rellenos de jam\u00f3n y queso. Date un homenaje en el Restaurante Sidrer\u00eda La Tropical (Av de Rufo Garc\u00eda Rendueles, 3).<\/p>\n<p>En bici por la ciudad<\/p>\n<p>El encanto de Gij\u00f3n se vive tambi\u00e9n en bicicleta. Recorrer su carril bici hasta el puerto deportivo es una aut\u00e9ntica delicia. En Ciclos Esplendor (C\/ La Merced 11 Esquina Francisco Mart\u00ednez Marina) puedes alquilar una y pasar el d\u00eda pedaleando y descubriendo la ciudad.<\/p>\n<figure class='caption' data-markdown='1'>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/96000\/96865.jpg\" alt=\"\" \/><figcaption>Con el buen tiempo el paseo mar\u00edtimo de llena de bicicletas  <br \/>A la playa en bicicleta courtesy \u00a92013 Manuel Creative Commons\/Flick<\/figcaption><\/figure>\n<p>Visitar el Jard\u00edn Bot\u00e1nico Atl\u00e1ntico<\/p>\n<p>Para perderse en un bosque de vegetaci\u00f3n boreal s\u00f3lo hay que ir a las afueras de Gij\u00f3n. En el Jard\u00edn Bot\u00e1nico (Av. del Jard\u00edn Bot\u00e1nico) se han recreado los paisajes del arco atl\u00e1ntico norte con especies como abedules, abetos rojos, sauces o hayas. Este maravilloso entorno ofrece adem\u00e1s sus Noches M\u00e1gicas con conciertos y otras iniciativas ideales para un plan diferente.<\/p>\n<figure class='caption' data-markdown='1'>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/96000\/96866.jpg\" alt=\"\" \/><figcaption>Detalle del jard\u00edn Bot\u00e1nico de Gij\u00f3n, un verdadero para\u00edso para los amantes de la naturaleza  <br \/>Bot\u00e1nico de Gij\u00f3n courtesy \u00a9 2008 Juanjo Minor Creative Commons\/Flick<\/figcaption><\/figure>\n<p>Dedicar tiempo al arte<\/p>\n<p>Cada esquina de Gij\u00f3n rebosa de arte, f\u00edjate bien en su <em>street art<\/em> al m\u00e1s puro estilo de Banksy. Existen museos y galer\u00edas de arte muy distintas, y para descubrir el sorprendente activismo por las nuevas vanguardias nada mejor que visitar la Laboral Centro de Arte y Creaci\u00f3n Industrial (Los Prados, 121). Tambi\u00e9n es una buena ocasi\u00f3n para conocer a dos de los grandes artistas asturianos en el museo dedicado a Nicanor Pi\u00f1ole (Plaza de Europa, 28) y en la Fundaci\u00f3n Museo Evaristo Valle (Camino Cabue\u00f1es, 261), un verdadero motor en la vida cultural gijonesa.<\/p>\n<figure class='caption' data-markdown='1'>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/96000\/96867.jpg\" alt=\"\" \/><figcaption>Edificio principal de la Fundaci\u00f3n Museo Evaristo Valle  <br \/>courtesy \u00a9 Fotograf\u00eda archivo fundaci\u00f3n Museo Evaristo Valle<\/figcaption><\/figure>\n<p>Curiosear sus tiendas<\/p>\n<p>Gij\u00f3n est\u00e1 repleto de curiosos negocios y tiendas tradicionales. P\u00e1rate a mirar libros y t\u00f3mate un caf\u00e9 en La librer\u00eda Central (Calle de San Bernardo, 31) y si eres m\u00e1s alternativo, busca vinilos en Paradiso (Calle de la Merced, 28). Pero si lo que te gusta son los planes de domingo, disfruta de m\u00fasica en directo en el Mercado del Museo del Ferrocarril (Plaza Estaci\u00f3n del Norte, s\/n) mientras descubres baratijas, productos ecol\u00f3gicos y tu lado m\u00e1s <em>vintage.<\/em><\/p>\n<p>Enamorarse de Cimadevilla<\/p>\n<p>La peque\u00f1a pen\u00ednsula de Cimadevilla es la perla de Gij\u00f3n. Este antiguo barrio de pescadores guarda un olor a mar inconfundible. Alternativo y desenfadado, su vida bulle de noche en locales en donde escuchar buena m\u00fasica: si te va el jazz, p\u00e1sate por El Patio de la Favorita (Ezcurdia, 4). De d\u00eda, no olvides contemplar a la estatua de Don Pelayo, ni tampoco descubrir quien era Jovellanos, pasear por la Plaza Mayor y quedarte maravillado ante la colegiata de San Juli\u00e1n Bautista.<\/p>\n<p>Saborear la mar<\/p>\n<p>Como buena ciudad marinera, los restaurantes de marisco abundan en sus calles. En La Zamorana (Avenida de los Hermanos Felgueroso, 38-40) puedes subir a las nubes probando un centollo del cant\u00e1brico y el <em>bugre<\/em> o bogavante. En cambio, si te llama la atenci\u00f3n la cocina de fusi\u00f3n, Auga (Calle de Claudio Alvargonz\u00e1lez, s\/n) es una excelente alternativa. Con el sabor de su tapa de erizos de mar te zambullir\u00e1s en el Atl\u00e1ntico.<\/p>\n<p>Tomar el sol en la playa de San Lorenzo<\/p>\n<p>Hay que aprovechar al m\u00e1ximo los t\u00edmidos rayos de sol del norte. Puedes hacerlo a pocos pasos del centro de la ciudad en la emblem\u00e1tica playa de Poniente o en la de San Lorenzo. Paralela a esta \u00faltima, discurre el paseo del Muro de San Lorenzo que se extiende hacia el este en la senda litoral del Cervig\u00f3n y lleva hacia las playas del Rincon\u00edn y de Pe\u00f1arrubia.<\/p>\n<p>Elogiar al horizonte<\/p>\n<p>El paisaje que se observa desde lo alto del cerro de Santa Catalina es imprescindible. Aqu\u00ed se disfruta de la mejor vista del Cant\u00e1brico fundiendo sus azules aguas a lo lejos con el cielo. Por esta raz\u00f3n Chillida dedic\u00f3 su particular obra a este espect\u00e1culo natural con el <em>Elogio del Horizonte<\/em> (Calle Cam\u00edn de la Fontica, s\/n), una descomunal escultura, que al situarte bajo la misma se oye el m\u00e1gico eco del romper de las olas.<\/p>\n<figure class='caption' data-markdown='1'>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/96000\/96868.jpg\" alt=\"\" \/><figcaption> Elogio del Horizonte de Chillida  <br \/>Elogio del Horizonte courtesy \u00a92010 Dibus y Deabus Creative Commons\/Flickr<\/figcaption><\/figure>\n<p>Fotograf\u00eda de portada: Escultura en el paseo mar\u00edtimo de Gij\u00f3n. Escultura Gij\u00f3n courtesy \u00a9 2015 Michel Curi Creative Commons\/Flickr&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gij\u00f3n: 10 cosas imprescindibles<\/p>\n","protected":false},"author":6,"featured_media":3616,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[85],"tags":[38],"authors":[],"class_list":["post-3610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-day-trips","tag-day-trips","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gij\u00f3n: 10 cosas imprescindibles | Explore de Expedia<\/title>\n<meta name=\"description\" content=\"Gij\u00f3n: 10 cosas imprescindibles\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.expedia.es\/stories\/gijon-10-cosas-imprescindibles\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gij\u00f3n: 10 cosas imprescindibles\" \/>\n<meta property=\"og:description\" content=\"Gij\u00f3n: 10 cosas imprescindibles\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.expedia.es\/stories\/gijon-10-cosas-imprescindibles\/\" \/>\n<meta property=\"og:site_name\" content=\"Expedia.es\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-12T03:07:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-01T22:06:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/17000\/17332-share-image.jpg\" \/>\n<meta name=\"author\" content=\"Expedia Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Expedia Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.expedia.es\/stories\/gijon-10-cosas-imprescindibles\/\",\"url\":\"https:\/\/www.expedia.es\/stories\/gijon-10-cosas-imprescindibles\/\",\"name\":\"Gij\u00f3n: 10 cosas imprescindibles | Explore de Expedia\",\"isPartOf\":{\"@id\":\"https:\/\/www.expedia.es\/stories\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.expedia.es\/stories\/gijon-10-cosas-imprescindibles\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.expedia.es\/stories\/gijon-10-cosas-imprescindibles\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.expedia.es\/stories\/wp-content\/uploads\/2021\/06\/17332-share-image.jpg\",\"datePublished\":\"2017-07-12T03:07:00+00:00\",\"dateModified\":\"2021-09-01T22:06:22+00:00\",\"author\":{\"@id\":\"https:\/\/www.expedia.es\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\"},\"description\":\"Gij\u00f3n: 10 cosas imprescindibles\",\"breadcrumb\":{\"@id\":\"https:\/\/www.expedia.es\/stories\/gijon-10-cosas-imprescindibles\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.expedia.es\/stories\/gijon-10-cosas-imprescindibles\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.es\/stories\/gijon-10-cosas-imprescindibles\/#primaryimage\",\"url\":\"https:\/\/www.expedia.es\/stories\/wp-content\/uploads\/2021\/06\/17332-share-image.jpg\",\"contentUrl\":\"https:\/\/www.expedia.es\/stories\/wp-content\/uploads\/2021\/06\/17332-share-image.jpg\",\"width\":1024,\"height\":685},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.expedia.es\/stories\/gijon-10-cosas-imprescindibles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Explore\",\"item\":\"https:\/\/www.expedia.es\/stories\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Excursiones\",\"item\":\"https:\/\/www.expedia.es\/stories\/day-trips\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gij\u00f3n: 10 cosas imprescindibles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.expedia.es\/stories\/#website\",\"url\":\"https:\/\/www.expedia.es\/stories\/\",\"name\":\"Expedia.es\",\"description\":\"Tu viaje comienza aqu\u00ed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.expedia.es\/stories\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.expedia.es\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\",\"name\":\"Expedia Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.es\/stories\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g\",\"caption\":\"Expedia Team\"},\"url\":\"https:\/\/www.expedia.es\/stories\/author\/expedia-team\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gij\u00f3n: 10 cosas imprescindibles | Explore de Expedia","description":"Gij\u00f3n: 10 cosas imprescindibles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.expedia.es\/stories\/gijon-10-cosas-imprescindibles\/","og_locale":"en_US","og_type":"article","og_title":"Gij\u00f3n: 10 cosas imprescindibles","og_description":"Gij\u00f3n: 10 cosas imprescindibles","og_url":"https:\/\/www.expedia.es\/stories\/gijon-10-cosas-imprescindibles\/","og_site_name":"Expedia.es","article_published_time":"2017-07-12T03:07:00+00:00","article_modified_time":"2021-09-01T22:06:22+00:00","og_image":[{"url":"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/17000\/17332-share-image.jpg"}],"author":"Expedia Team","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Expedia Team","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.expedia.es\/stories\/gijon-10-cosas-imprescindibles\/","url":"https:\/\/www.expedia.es\/stories\/gijon-10-cosas-imprescindibles\/","name":"Gij\u00f3n: 10 cosas imprescindibles | Explore de Expedia","isPartOf":{"@id":"https:\/\/www.expedia.es\/stories\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.expedia.es\/stories\/gijon-10-cosas-imprescindibles\/#primaryimage"},"image":{"@id":"https:\/\/www.expedia.es\/stories\/gijon-10-cosas-imprescindibles\/#primaryimage"},"thumbnailUrl":"https:\/\/www.expedia.es\/stories\/wp-content\/uploads\/2021\/06\/17332-share-image.jpg","datePublished":"2017-07-12T03:07:00+00:00","dateModified":"2021-09-01T22:06:22+00:00","author":{"@id":"https:\/\/www.expedia.es\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389"},"description":"Gij\u00f3n: 10 cosas imprescindibles","breadcrumb":{"@id":"https:\/\/www.expedia.es\/stories\/gijon-10-cosas-imprescindibles\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.expedia.es\/stories\/gijon-10-cosas-imprescindibles\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.es\/stories\/gijon-10-cosas-imprescindibles\/#primaryimage","url":"https:\/\/www.expedia.es\/stories\/wp-content\/uploads\/2021\/06\/17332-share-image.jpg","contentUrl":"https:\/\/www.expedia.es\/stories\/wp-content\/uploads\/2021\/06\/17332-share-image.jpg","width":1024,"height":685},{"@type":"BreadcrumbList","@id":"https:\/\/www.expedia.es\/stories\/gijon-10-cosas-imprescindibles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Explore","item":"https:\/\/www.expedia.es\/stories\/"},{"@type":"ListItem","position":2,"name":"Excursiones","item":"https:\/\/www.expedia.es\/stories\/day-trips\/"},{"@type":"ListItem","position":3,"name":"Gij\u00f3n: 10 cosas imprescindibles"}]},{"@type":"WebSite","@id":"https:\/\/www.expedia.es\/stories\/#website","url":"https:\/\/www.expedia.es\/stories\/","name":"Expedia.es","description":"Tu viaje comienza aqu\u00ed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.expedia.es\/stories\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.expedia.es\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389","name":"Expedia Team","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.es\/stories\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g","caption":"Expedia Team"},"url":"https:\/\/www.expedia.es\/stories\/author\/expedia-team\/"}]}},"_links":{"self":[{"href":"https:\/\/www.expedia.es\/stories\/wp-json\/wp\/v2\/posts\/3610"}],"collection":[{"href":"https:\/\/www.expedia.es\/stories\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.expedia.es\/stories\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.expedia.es\/stories\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.expedia.es\/stories\/wp-json\/wp\/v2\/comments?post=3610"}],"version-history":[{"count":1,"href":"https:\/\/www.expedia.es\/stories\/wp-json\/wp\/v2\/posts\/3610\/revisions"}],"predecessor-version":[{"id":7117,"href":"https:\/\/www.expedia.es\/stories\/wp-json\/wp\/v2\/posts\/3610\/revisions\/7117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.expedia.es\/stories\/wp-json\/wp\/v2\/media\/3616"}],"wp:attachment":[{"href":"https:\/\/www.expedia.es\/stories\/wp-json\/wp\/v2\/media?parent=3610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.expedia.es\/stories\/wp-json\/wp\/v2\/categories?post=3610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.expedia.es\/stories\/wp-json\/wp\/v2\/tags?post=3610"},{"taxonomy":"authors","embeddable":true,"href":"https:\/\/www.expedia.es\/stories\/wp-json\/wp\/v2\/authors?post=3610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}